{"id":57843,"date":"2024-02-29T12:20:21","date_gmt":"2024-02-29T11:20:21","guid":{"rendered":"https:\/\/verandair-pro.poush-dev.be\/?page_id=57843"},"modified":"2026-02-27T14:48:00","modified_gmt":"2026-02-27T13:48:00","slug":"garantie","status":"publish","type":"page","link":"https:\/\/www.verandair.com\/fr\/garantie\/","title":{"rendered":"Garantie"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#ffffff 30%|rgba(255,255,255,0.95) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/01\/VERANDAIR-veranda.jpg&#8221; custom_padding=&#8221;||150px||false|false&#8221; custom_padding_tablet=&#8221;||150px||false|false&#8221; custom_padding_phone=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_breadcrumbs home_text=&#8221; &#8221; home_icon=&#8221;&#xe009;||divi||400&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_breadcrumbs][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Les <b style=\"font-weight: 400;\">garanties <\/b>VERANDAIR\u00ae<\/h1>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;2adabd0f-cb12-404f-9aa7-a3088280e564&#8243; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5298e62e-f7ac-4dd9-b361-006fc4da68de&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Nos <strong>garanties<\/strong> Belgique<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5298e62e-f7ac-4dd9-b361-006fc4da68de&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Conform\u00e9ment \u00e0 nos conditions g\u00e9n\u00e9rales de vente,\u00a0<strong>la garantie l\u00e9gale de 2 ans est d\u2019application<\/strong>\u00a0(*).<\/p>\n<p>3. Sans pr\u00e9judice des garanties l\u00e9gales pr\u00e9cit\u00e9es, le client b\u00e9n\u00e9ficie des\u00a0<strong>garanties \u201ccommerciales\u201d (**) suivantes<\/strong>\u00a0s\u2019agissant des abris fabriqu\u00e9s par la soci\u00e9t\u00e9 VERANDAIR :<\/p>\n<ul>\n<li>15 ans sur la structure en aluminium de l\u2019abri (ossature et \u00e9querres d\u2019assemblage) la constituant<\/li>\n<li>10 ans sur le laquage<\/li>\n<li>10 ans sur le vitrage<\/li>\n<li>10 ans sur les feuilles de polycarbonate ou en mat\u00e9riaux composites pour la toiture<\/li>\n<li>2 ans sur les joints de silicone<\/li>\n<li>2 ans sur la visserie, quincaillerie et toutes les pi\u00e8ces inh\u00e9rentes a\u0300 l\u2019abri en dehors des points (a,b,c,d)<\/li>\n<li>2 ans sur les stores, le mat\u00e9riel \u00e9lectrique (par ex. \u00e9clairages, motorisations, t\u00e9l\u00e9commandes)<\/li>\n<\/ul>\n<p>Les d\u00e9fauts esth\u00e9tiques li\u00e9s au temps et \u00e0 l\u2019usure naturelle ne remettent pas en cause l\u2019utilisation de l\u2019abri. La garantie des diff\u00e9rents \u00e9l\u00e9ments de votre abri ou pergola VERANDAIR\u00ae ne pourra s\u2019appliquer en cas d\u2019absence manifeste d\u2019entretien ou si l\u2019emploi de produits non adapt\u00e9s est constat\u00e9. Les diff\u00e9rentes garanties ne sont applicables que dans la mesure o\u00f9 la structure de l\u2019abri ou de la pergola n\u2019est pas modifi\u00e9e.<\/p>\n<p><em>(*) La r\u00e9ception de l\u2019ouvrage, expresse ou tacite, marque le point de d\u00e9part des garanties l\u00e9gales et conventionnelles applicables, pour autant que l\u2019int\u00e9gralit\u00e9 des montants dus ait e\u0301te\u0301 r\u00e9gl\u00e9e par le client.<\/em><\/p>\n<p><em>(**) Ces garanties \u201ccommerciales\u201d ne sont applicables qu\u2019en cas de paiement int\u00e9gral des montants dus aux \u00e9ch\u00e9ances fix\u00e9es.<\/em><\/p>\n<p>Vous trouverez tous les d\u00e9tails d\u2019application de nos garanties dans nos conditions g\u00e9n\u00e9rales de vente.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_masonry_gallery gallery_ids=&#8221;58070,57725,57530,2656,2130,57355,57244,57196,1846,1834,1819,1670,1570,1561&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_masonry_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#ffffff 30%|rgba(255,255,255,0.95) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/01\/VERANDAIR-veranda.jpg&#8221; custom_padding=&#8221;||150px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300||on|||||&#8221; text_font_size=&#8221;16px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Les garanties<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Activation de la <b style=\"font-weight: 400;\">garantie commerciale<\/b><\/h2>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;2adabd0f-cb12-404f-9aa7-a3088280e564&#8243; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5298e62e-f7ac-4dd9-b361-006fc4da68de&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Une fois l\u2019installation de votre abri termin\u00e9e et pay\u00e9e, nous vous invitons \u00e0 activer votre garantie commerciale sur notre site \u00e0 l\u2019aide de votre code. Ce code vous sera envoy\u00e9 via courriel ou par voie postale.<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;800px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div id=\"formactG\"><!-- [et_pb_line_break_holder] -->  \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f60121-o1\" lang=\"fr-FR\" dir=\"ltr\" data-wpcf7-id=\"60121\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/57843#wpcf7-f60121-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulaire de contact\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"60121\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f60121-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"dossier-num\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Votre num\u00e9ro de dossier (4 chiffres)\" value=\"\" type=\"text\" name=\"dossier-num\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"address\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adresse\" value=\"\" type=\"text\" name=\"address\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"zipcode\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Code Postal\" value=\"\" type=\"text\" name=\"zipcode\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ville\" value=\"\" type=\"text\" name=\"city\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Pays\" value=\"\" type=\"text\" name=\"country\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone\" value=\"\" type=\"text\" name=\"phone\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Adresse Email\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"code\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Code d\u2019activation de la garantie \u00e0 4 chiffres\" value=\"\" type=\"text\" name=\"code\" \/><\/span><br \/>\n<em>D\u00e9livr\u00e9 par la soci\u00e9t\u00e9 POOL COVER apr\u00e8s\u00a0r\u00e9ception d\u00e9finitive et paiement int\u00e9gral<\/em>\n<\/p>\n<p><span id=\"wpcf7-6a57550a025f3-wrapper\" class=\"wpcf7-form-control-wrap numero-serie-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a57550a025f3-field\" class=\"hp-message\">Veuillez laisser ce champ vide.<\/label><input id=\"wpcf7-6a57550a025f3-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"numero-serie\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<p><button class=\"wpcf7-form-control wpcf7-submit has-spinner et_pb_button et_pb_bg_layout_light\" type=\"submit\" value=\"Envoyer la demande\">Envoyer la demande<\/button>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;gcid-a78bba3e-9a00-4c62-8b29-47f3d6c30097&#8243; background_image=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/01\/verandair-abri-terrasse-retractable-2.jpg&#8221; background_blend=&#8221;multiply&#8221; z_index=&#8221;10&#8243; custom_padding=&#8221;0px||80px||false|false&#8221; global_colors_info=&#8221;{%22gcid-a78bba3e-9a00-4c62-8b29-47f3d6c30097%22:%91%22background_color%22%93}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||50px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/01\/showroom-verandair-veranda-et-pergola.jpeg&#8221; title_text=&#8221;showroom-verandair-veranda-et-pergola&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;b56c1d61-e3cb-420b-8a4f-0c33bcdf9398&#8243; custom_margin=&#8221;-80px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;80px||||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;5298e62e-f7ac-4dd9-b361-006fc4da68de&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.9em&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||35px||false|false&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Notre <strong>showroom<\/strong><br \/><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiNDJrcExzUGY2N0VsN0FkMldFdElreCIsInBhc3RlSUQiOjI1NDM4MDY0MSwiZGF0YVR5cGUiOiJzY2VuZSJ9Cg==(\/figmeta)--&gt;\"><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;2adabd0f-cb12-404f-9aa7-a3088280e564&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5298e62e-f7ac-4dd9-b361-006fc4da68de&#8221; text_line_height=&#8221;1.9em&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||50px||false|false&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-ghsik-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-ghsik-1n7m0yu\">\n<div class=\"flex flex-col text-sm pb-9\">\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-65\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\n<div class=\"relative flex w-full flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"8cdd3d8c-bb16-45e1-80dd-eb13069f8f4d\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Choisir une v\u00e9randa pour votre domicile est une d\u00e9marche qui combine r\u00e9flexion et cr\u00e9ativit\u00e9. Nous sommes l\u00e0 pour vous accompagner. <strong>D\u00e9couvrez nos divers mod\u00e8les en visitant nos showrooms<\/strong> en Belgique, o\u00f9 vous pourrez poser toutes vos questions. Notre espace d&#8217;exposition de <strong>650m\u00b2 \u00e0 Spy<\/strong>, inaugur\u00e9 en octobre 2017, vous offre une immersion dans notre gamme de v\u00e9randas, pergolas, et plus encore, vous permettant de les appr\u00e9cier en conditions r\u00e9elle.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjU5MCJ9fQ==@&#8221; button_text=&#8221;Tout savoir sur VERANDAIR\u00ae&#8221; _builder_version=&#8221;4.24.0&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;8ac6895b-8a7d-4b15-8635-28e44651343f&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{%22gcid-cdfc5e12-aa04-4e46-8d7a-a46e0d249000%22:%91%22button_text_color%22%93}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_module=&#8221;1235&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221; custom_css_main_element_phone=&#8221;max-width: 50%;&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/01\/VERANDAIR-sur-mesure-w.svg&#8221; title_text=&#8221;VERANDAIR-sur-mesure-w&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;120px&#8221; width_tablet=&#8221;120px&#8221; width_phone=&#8221;80px&#8221; width_last_edited=&#8221;on|phone&#8221; max_width=&#8221;120px&#8221; max_width_tablet=&#8221;120px&#8221; max_width_phone=&#8221;80px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; animation_style=&#8221;fade&#8221; animation_duration=&#8221;500ms&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_phone=&#8221;max-width: 50%;&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2026\/01\/VERANDAIR-garantie-w.svg&#8221; title_text=&#8221;VERANDAIR-garantie-w&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;120px&#8221; width_tablet=&#8221;120px&#8221; width_phone=&#8221;80px&#8221; width_last_edited=&#8221;on|tablet&#8221; max_width=&#8221;120px&#8221; max_width_tablet=&#8221;120px&#8221; max_width_phone=&#8221;80px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; animation_style=&#8221;fade&#8221; animation_duration=&#8221;500ms&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_phone=&#8221;max-width: 50%;&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2026\/02\/VERANDAIR-experience-w.svg&#8221; title_text=&#8221;VERANDAIR-experience-w&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;120px&#8221; width_tablet=&#8221;120px&#8221; width_phone=&#8221;80px&#8221; width_last_edited=&#8221;on|tablet&#8221; max_width=&#8221;120px&#8221; max_width_tablet=&#8221;120px&#8221; max_width_phone=&#8221;80px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; animation_style=&#8221;fade&#8221; animation_duration=&#8221;500ms&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; custom_css_main_element_phone=&#8221;max-width: 50%;&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2026\/01\/VERANDAIR-projets-realises-w.svg&#8221; title_text=&#8221;VERANDAIR-projets-realises-w&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;120px&#8221; width_tablet=&#8221;120px&#8221; width_phone=&#8221;80px&#8221; width_last_edited=&#8221;on|tablet&#8221; max_width=&#8221;120px&#8221; max_width_tablet=&#8221;120px&#8221; max_width_phone=&#8221;80px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; animation_style=&#8221;fade&#8221; animation_duration=&#8221;500ms&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/01\/VERANDAIR-fabrication-belge-w.svg&#8221; title_text=&#8221;VERANDAIR-fabrication-belge-w&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;120px&#8221; width_tablet=&#8221;120px&#8221; width_phone=&#8221;80px&#8221; width_last_edited=&#8221;on|tablet&#8221; max_width=&#8221;120px&#8221; max_width_tablet=&#8221;120px&#8221; max_width_phone=&#8221;80px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; animation_style=&#8221;fade&#8221; animation_duration=&#8221;500ms&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;a37cb46d-a9cb-4f77-bbbd-8966bde7aff0&#8243; z_index=&#8221;10&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; global_module=&#8221;74561&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2026\/02\/VERAN-brochure-A4-2026.webp&#8221; title_text=&#8221;VERAN-brochure-A4-2026&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;b096e94b-b449-482c-93dd-aaf145b3f96d&#8221; scroll_vertical_motion_enable=&#8221;on&#8221; scroll_vertical_motion=&#8221;0|40|40|100|-0.5|0|0&#8243; scroll_fade_enable=&#8221;on&#8221; scroll_fade=&#8221;0|40|40|100|0|100|100&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; alt=&#8221;Brochure 2026 Verandair&#8221; max_width=&#8221;500px&#8221; sticky_enabled=&#8221;0&#8243; custom_margin=&#8221;0px||0px||false|false&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||35px||false|false&#8221; global_colors_info=&#8221;{%22gcid-4f3ca7d5-152d-4540-91b1-cc24563bf794%22:%91%22text_text_shadow_color%22%93}&#8221;]<\/p>\n<h2><strong>Envie d&#8217;en savoir plus<\/strong> avant de vous d\u00e9cider ?<br \/><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiNDJrcExzUGY2N0VsN0FkMldFdElreCIsInBhc3RlSUQiOjI4MTE1MTAxNSwiZGF0YVR5cGUiOiJzY2VuZSJ9Cg==(\/figmeta)--&gt;\"><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;2adabd0f-cb12-404f-9aa7-a3088280e564&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||50px||false|false&#8221; global_colors_info=&#8221;{%22gcid-4f3ca7d5-152d-4540-91b1-cc24563bf794%22:%91%22text_text_shadow_color%22%93}&#8221;]<\/p>\n<p><span><strong>T\u00e9l\u00e9chargez la nouvelle brochure 2026<\/strong>\u00a0et d\u00e9couvrez notre <strong>gamme compl\u00e8te de produits<\/strong> pour profiter de votre vie en plein air toute l&#8217;ann\u00e9e.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;ttps:\/\/info.verandair.com\/brochure-2026\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Je t\u00e9l\u00e9charge ma brochure&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;ae8d3791-01a2-4c4b-b221-c3f14f812284&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_breadcrumbs dsm_breadcrumbs_0 et_animated\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<nav class=\"dsm_breadcrumbs_wrap\">\n\t\t\t\t<ul class=\"dsm_breadcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\t\t\t<li class=\"dsm_breadcrumbs_item dsm_home_item dsm_home_item_custom\" itemprop=\"itemListElement\" itemscope\n\t\t\titemtype=\"https:\/\/schema.org\/ListItem\">\n\t\t\t\t<a href=\"https:\/\/www.verandair.com\/fr\/\" itemprop=\"item\" target=\"\">\n\t\t\t\t\t<span class='dsm_home_text_wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"et-pb-icon dsm_home_icon\">&#xe009;<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"dsm_home_text\" itemprop=\"name\">\n\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<meta itemprop=\"position\" content=\"1\" \/>\n\t\t\t<\/li>\n\n\t\t<li class=\"dsm_breadcrumbs_separator\"> <span class=\"et-pb-icon dsm_separator_icon\">&#x35;<\/span><\/li><\/ul>\n\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Les garanties VERANDAIR\u00aeNos garanties BelgiqueConform\u00e9ment \u00e0 nos conditions g\u00e9n\u00e9rales de vente,\u00a0la garantie l\u00e9gale de 2 ans est d\u2019application\u00a0(*). 3. Sans pr\u00e9judice des garanties l\u00e9gales pr\u00e9cit\u00e9es, le client b\u00e9n\u00e9ficie des\u00a0garanties \u201ccommerciales\u201d (**) suivantes\u00a0s\u2019agissant des abris fabriqu\u00e9s par la soci\u00e9t\u00e9 VERANDAIR : 15 ans sur la structure en aluminium de l\u2019abri (ossature et \u00e9querres d\u2019assemblage) la constituant 10 ans sur le laquage 10 ans sur le vitrage 10 ans sur les feuilles de polycarbonate ou en mat\u00e9riaux composites pour la toiture 2 ans sur les joints de silicone 2 ans sur la visserie, quincaillerie et toutes les pi\u00e8ces inh\u00e9rentes a\u0300 l\u2019abri en dehors des points (a,b,c,d) 2 ans sur les stores, le mat\u00e9riel \u00e9lectrique (par ex. \u00e9clairages, motorisations, t\u00e9l\u00e9commandes) Les d\u00e9fauts esth\u00e9tiques li\u00e9s au temps et \u00e0 l\u2019usure naturelle ne remettent pas en cause l\u2019utilisation de l\u2019abri. La garantie des diff\u00e9rents \u00e9l\u00e9ments de votre abri ou pergola VERANDAIR\u00ae ne pourra s\u2019appliquer en cas d\u2019absence manifeste d\u2019entretien ou si l\u2019emploi de produits non adapt\u00e9s est constat\u00e9. Les diff\u00e9rentes garanties ne sont applicables que dans la mesure o\u00f9 la structure de l\u2019abri ou de la pergola n\u2019est pas modifi\u00e9e. (*) La r\u00e9ception de l\u2019ouvrage, expresse ou tacite, marque [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-57843","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garantie | VERANDAIR\u00ae<\/title>\n<meta name=\"description\" content=\"Pergolas et v\u00e9randas Verandair garanties : structure aluminium durable, service apr\u00e8s-vente r\u00e9actif et installation professionnelle irr\u00e9prochable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.verandair.com\/fr\/garantie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garantie | VERANDAIR\u00ae\" \/>\n<meta property=\"og:description\" content=\"Pergolas et v\u00e9randas Verandair garanties : structure aluminium durable, service apr\u00e8s-vente r\u00e9actif et installation professionnelle irr\u00e9prochable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.verandair.com\/fr\/garantie\/\" \/>\n<meta property=\"og:site_name\" content=\"VERANDAIR\u00ae\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T13:48:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/garantie\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/garantie\\\/\",\"name\":\"Garantie | VERANDAIR\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-02-29T11:20:21+00:00\",\"dateModified\":\"2026-02-27T13:48:00+00:00\",\"description\":\"Pergolas et v\u00e9randas Verandair garanties : structure aluminium durable, service apr\u00e8s-vente r\u00e9actif et installation professionnelle irr\u00e9prochable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/garantie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.verandair.com\\\/fr\\\/garantie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/garantie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garantie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"VERANDAIR\u00ae\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\",\"name\":\"Verandair\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"width\":283,\"height\":127,\"caption\":\"Verandair\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garantie | VERANDAIR\u00ae","description":"Pergolas et v\u00e9randas Verandair garanties : structure aluminium durable, service apr\u00e8s-vente r\u00e9actif et installation professionnelle irr\u00e9prochable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.verandair.com\/fr\/garantie\/","og_locale":"fr_FR","og_type":"article","og_title":"Garantie | VERANDAIR\u00ae","og_description":"Pergolas et v\u00e9randas Verandair garanties : structure aluminium durable, service apr\u00e8s-vente r\u00e9actif et installation professionnelle irr\u00e9prochable.","og_url":"https:\/\/www.verandair.com\/fr\/garantie\/","og_site_name":"VERANDAIR\u00ae","article_modified_time":"2026-02-27T13:48:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/garantie\/","url":"https:\/\/www.verandair.com\/fr\/garantie\/","name":"Garantie | VERANDAIR\u00ae","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/#website"},"datePublished":"2024-02-29T11:20:21+00:00","dateModified":"2026-02-27T13:48:00+00:00","description":"Pergolas et v\u00e9randas Verandair garanties : structure aluminium durable, service apr\u00e8s-vente r\u00e9actif et installation professionnelle irr\u00e9prochable.","breadcrumb":{"@id":"https:\/\/www.verandair.com\/fr\/garantie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.verandair.com\/fr\/garantie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.verandair.com\/fr\/garantie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/","name":"Accueil"}},{"@type":"ListItem","position":2,"name":"Garantie"}]},{"@type":"WebSite","@id":"https:\/\/www.verandair.com\/fr\/#website","url":"https:\/\/www.verandair.com\/fr\/","name":"VERANDAIR\u00ae","description":"","publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.verandair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.verandair.com\/fr\/#organization","name":"Verandair","url":"https:\/\/www.verandair.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","width":283,"height":127,"caption":"Verandair"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/pages\/57843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/comments?post=57843"}],"version-history":[{"count":13,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/pages\/57843\/revisions"}],"predecessor-version":[{"id":74569,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/pages\/57843\/revisions\/74569"}],"wp:attachment":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media?parent=57843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}