{"id":18861,"date":"2021-02-01T16:38:22","date_gmt":"2021-02-01T15:38:22","guid":{"rendered":"https:\/\/www.verandair.com\/?p=18861"},"modified":"2026-02-27T15:25:59","modified_gmt":"2026-02-27T14:25:59","slug":"nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai","status":"publish","type":"post","link":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/","title":{"rendered":"Nos conseillers commerciaux vous accompagnent dans nos showrooms de Namur et Tournai"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Opter pour une solution de pergola pour votre jardin ou d\u2019abri r\u00e9tractable pour votre terrasse ou votre piscine est une <strong>d\u00e9cision qui doit \u00eatre m\u00fbrement r\u00e9fl\u00e9chie<\/strong>. Compte tenu des changements majeurs qu\u2019une telle installation va apporter \u00e0 votre propri\u00e9t\u00e9 et du budget \u00e0 y consacrer, il est important d\u2019avoir une parfaite id\u00e9e de toutes les possibilit\u00e9s qui s\u2019offrent \u00e0 vous et de ce qu\u2019elles impliquent.<\/p>\n<p>C\u2019est pourquoi, chez <a href=\"https:\/\/www.verandair.com\/fr\/\">VERANDAIR<\/a>, nous mettons un point d\u2019honneur \u00e0 vous offrir un <strong>accompagnement personnalis\u00e9 et de qualit\u00e9<\/strong>. \u00c0 travers des personnes de contact choisies pour leurs connaissances pointues de notre entreprise et de notre m\u00e9tier, vous obtenez les meilleurs conseils afin d\u2019\u00eatre toujours s\u00fbr de faire les bons choix.<\/p>\n<p><strong>Ces personnes de confiance<\/strong>, ce sont celles que vous rencontrez en vous rendant dans l\u2019un de nos showrooms, \u00e0 Namur (Spy) ou \u00e0 Tournai, <strong>ce sont nos pr\u00e9cieux<\/strong> <strong>conseillers commerciaux<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #00909e;\">Plus que des conseillers commerciaux, des hommes de m\u00e9tier<\/span><\/h2>\n<p>Nos conseillers commerciaux, nous les avons choisis pour leur <strong>exp\u00e9rience concr\u00e8te et leurs connaissances des r\u00e9alit\u00e9s du terrain<\/strong> li\u00e9es \u00e0 l\u2019installation de <a href=\"https:\/\/www.verandair.com\/fr\/veranda\/\">nos abris<\/a>. Aucun d\u2019entre eux n\u2019est vendeur de formation mais bien <strong>ouvrier exp\u00e9riment\u00e9<\/strong>. Leurs qualit\u00e9s en tant que conseillers commerciaux, ils les doivent uniquement \u00e0 leur parcours. C\u2019est pourquoi nous consid\u00e9rons qu\u2019ils sont <strong>les personnes les mieux plac\u00e9es pour comprendre vos attentes et d\u00e9finir votre projet<\/strong>. C\u2019est \u00e9galement pour cette raisons que nous leur accordons <strong>toute notre confiance<\/strong> quant \u00e0 l\u2019accompagnement de chacun de nos clients.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3 style=\"text-align: left;\"><span style=\"color: #00909e;\">Dominique vous accueille \u00e0 Namur<\/span><\/h3>\n<p style=\"text-align: left;\"><strong>Dominique Vincart<\/strong> est pr\u00e9sent depuis de nombreuses ann\u00e9es au sein de VERANDAIR. Il est <strong>menuisier de formation<\/strong> et a d\u00e9marr\u00e9 sa carri\u00e8re dans le p\u00f4le construction de notre entreprise. En <strong>35 ans de m\u00e9tier<\/strong>, il a exp\u00e9riment\u00e9 toutes les \u00e9tapes de <strong>conception<\/strong> et d\u2019<strong>installation<\/strong> de nos abris r\u00e9tractables avant de devenir conseiller en showroom. Autant dire qu\u2019il <strong>conna\u00eet parfaitement nos produits<\/strong> et la mani\u00e8re dont ils sont con\u00e7us. Tous les cas de figure possibles lors de l\u2019installation d\u2019un abri, il les a d\u00e9j\u00e0 rencontr\u00e9s au cours de son travail sur le terrain. C\u2019est donc sur base d\u2019une exp\u00e9rience r\u00e9elle qu\u2019il pourra <strong>vous conseiller<\/strong> dans le choix de votre <a href=\"https:\/\/www.verandair.com\/fr\/veranda\/verandas-retractables\/\">v\u00e9randa r\u00e9tractable <\/a>ou votre <a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/\">pergola<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_divider][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/01\/vincent.png&#8221; alt=&#8221;V\u00e9randa V\u00e9randair pour votre maison&#8221; title_text=&#8221;V\u00e9randa V\u00e9randair pour votre maison&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3 style=\"text-align: left;\"><span style=\"color: #00909e;\">Christophe vous accueille \u00e0 Tournai<\/span><\/h3>\n<p style=\"text-align: left;\"><strong>Christophe Surmont<\/strong>, comme l\u2019ensemble de nos conseillers commerciaux, est <strong>menuisier de formation<\/strong>. Riche de 30 ann\u00e9es d\u2019exp\u00e9rience en atelier et sur chantier, il a rejoint l\u2019entreprise VERANDAIR afin de <strong>vous faire profiter de son expertise<\/strong> dans notre showroom de Tournai. Il vous y accueille avec plaisir pour \u00e9laborer avec vous tous les aspects de votre projet de construction. Gr\u00e2ce \u00e0 ses <strong>connaissances des r\u00e9alit\u00e9s du terrain<\/strong>, il se place comme un alli\u00e9 de choix dans votre <strong>accompagnement personnalis\u00e9<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/01\/dominique.png&#8221; alt=&#8221;V\u00e9randa V\u00e9randair pour votre maison&#8221; title_text=&#8221;V\u00e9randa V\u00e9randair pour votre maison&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_orientation=&#8221;justified&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3 style=\"text-align: left;\"><span style=\"color: #00909e;\">Vincent vous accueille \u00e0 Namur<\/span><\/h3>\n<p style=\"text-align: left;\"><strong>Vincent Rahmani<\/strong> est le plus jeune de nos conseillers. Il b\u00e9n\u00e9ficie n\u00e9anmoins d\u2019une <strong>exp\u00e9rience de 10 ans<\/strong> chez VERANDAIR, dont il connait \u00e9galement tous les axes. Durant cette p\u00e9riode, il a pu apprendre les subtilit\u00e9s techniques de nos abris en tant que <strong>menuisier en atelier<\/strong>, mais \u00e9galement en tant qu\u2019<strong>installateur sur chantier<\/strong>. Son attrait pour le contact avec les clients l\u2019a naturellement men\u00e9 vers le conseil en showroom. Gr\u00e2ce \u00e0 lui, vous obtiendrez une vision claire de toutes les possibilit\u00e9s qui s\u2019offrent \u00e0 vous lors de l\u2019installation d\u2019un de nos abris r\u00e9tractables.<\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_divider][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/01\/christophe.png&#8221; alt=&#8221;V\u00e9randa V\u00e9randair pour votre maison&#8221; title_text=&#8221;V\u00e9randa V\u00e9randair pour votre maison&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2><span style=\"color: #00909e;\">Leur priorit\u00e9, c&#8217;est votre projet<\/span><\/h2>\n<p>Que votre envie d\u2019abri r\u00e9tractable ou de pergola en soit \u00e0 ses balbutiements ou que votre projet soit d\u00e9j\u00e0 bien \u00e9tabli dans votre t\u00eate, <strong>nos conseillers commerciaux vous guident en direct sur les meilleures options \u00e0 adopter<\/strong>. Ils \u00e9laborent ensuite avec vous, pas \u00e0 pas, tous les aspects de votre future construction afin que vous en obteniez un <strong>plan concret et tangible<\/strong>. Quoi qu\u2019il arrive, ils chercheront toujours <strong>les solutions qui r\u00e9pondent le plus \u00e0 vos attentes<\/strong> et non celles qui viennent simplement ajouter des lignes \u00e0 votre devis. Gr\u00e2ce \u00e0 nos super conseillers commerciaux, nous sommes en mesure de vous <strong>garantir une totale satisfaction quant \u00e0 la qualit\u00e9 de notre service d\u2019accompagnement <\/strong>(en plus de la qualit\u00e9 de nos diff\u00e9rents produits, bien s\u00fbr).<\/p>\n<p>Venez \u00e0 la leur rencontre. Ils sont pr\u00e9sents dans nos showrooms \u00e0 <a href=\"https:\/\/www.verandair.com\/fr\/rendez-vous-namur\/\">Namur<\/a> (Spy) et <a href=\"https:\/\/www.verandair.com\/fr\/rendez-vous-tournai\/\">Tournai<\/a> et sont l\u00e0 pour <strong>r\u00e9pondre \u00e0 toutes vos interrogations<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;a37cb46d-a9cb-4f77-bbbd-8966bde7aff0&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; global_module=&#8221;74566&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px|20px||20px|false|true&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;50px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2026\/02\/VERAN-brochure-A4-2026.webp&#8221; alt=&#8221;Brochure 2026 Verandair&#8221; title_text=&#8221;VERAN-brochure-A4-2026&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;300px&#8221; max_width_last_edited=&#8221;off|desktop&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; scroll_vertical_motion_enable=&#8221;on&#8221; scroll_vertical_motion=&#8221;0|40|40|100|-0.5|0|0&#8243; scroll_fade_enable=&#8221;on&#8221; scroll_fade=&#8221;0|40|40|100|0|100|100&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_2_font_size=&#8221;32px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||15px||false|false&#8221; global_colors_info=&#8221;{%22gcid-4f3ca7d5-152d-4540-91b1-cc24563bf794%22:%91%22text_text_shadow_color%22%93}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2><strong>Envie d&#8217;en savoir plus<\/strong> avant de vous d\u00e9cider ?<br \/><span data-metadata=\"&lt;!--(figmeta)eyJmaWxlS2V5IjoiNDJrcExzUGY2N0VsN0FkMldFdElreCIsInBhc3RlSUQiOjI4MTE1MTAxNSwiZGF0YVR5cGUiOiJzY2VuZSJ9Cg==(\/figmeta)--&gt;\"><\/span><\/h2>\n<p>[\/et_pb_text][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;2adabd0f-cb12-404f-9aa7-a3088280e564&#8243; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||50px||false|false&#8221; global_colors_info=&#8221;{%22gcid-4f3ca7d5-152d-4540-91b1-cc24563bf794%22:%91%22text_text_shadow_color%22%93}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p><span><strong>T\u00e9l\u00e9chargez la nouvelle brochure 2026<\/strong>\u00a0et d\u00e9couvrez notre <strong>gamme compl\u00e8te de produits<\/strong> pour profiter de votre vie en plein air toute l&#8217;ann\u00e9e.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/info.verandair.com\/brochure-2026\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Je t\u00e9l\u00e9charge ma brochure&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;ae8d3791-01a2-4c4b-b221-c3f14f812284&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opter pour une solution de pergola pour votre jardin ou d\u2019abri r\u00e9tractable pour votre terrasse ou votre piscine est une d\u00e9cision qui doit \u00eatre m\u00fbrement r\u00e9fl\u00e9chie. Compte tenu des changements majeurs qu\u2019une telle installation va apporter \u00e0 votre propri\u00e9t\u00e9 et du budget \u00e0 y consacrer, il est important d\u2019avoir une parfaite id\u00e9e de toutes les possibilit\u00e9s qui s\u2019offrent \u00e0 vous et de ce qu\u2019elles impliquent. C\u2019est pourquoi, chez VERANDAIR, nous mettons un point d\u2019honneur \u00e0 vous offrir un accompagnement personnalis\u00e9 et de qualit\u00e9. \u00c0 travers des personnes de contact choisies pour leurs connaissances pointues de notre entreprise et de notre m\u00e9tier, vous obtenez les meilleurs conseils afin d\u2019\u00eatre toujours s\u00fbr de faire les bons choix. Ces personnes de confiance, ce sont celles que vous rencontrez en vous rendant dans l\u2019un de nos showrooms, \u00e0 Namur (Spy) ou \u00e0 Tournai, ce sont nos pr\u00e9cieux conseillers commerciaux. &nbsp; Plus que des conseillers commerciaux, des hommes de m\u00e9tier Nos conseillers commerciaux, nous les avons choisis pour leur exp\u00e9rience concr\u00e8te et leurs connaissances des r\u00e9alit\u00e9s du terrain li\u00e9es \u00e0 l\u2019installation de nos abris. Aucun d\u2019entre eux n\u2019est vendeur de formation mais bien ouvrier exp\u00e9riment\u00e9. Leurs qualit\u00e9s en tant que conseillers commerciaux, ils les doivent [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17421,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-18861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos conseillers commerciaux \u00e0 Namur et \u00e0 Tournai | Experts VERANDAIR<\/title>\n<meta name=\"description\" content=\"Nos conseillers commerciaux vous aident dans la r\u00e9alisation de votre projet d&#039;abri r\u00e9tractable. Qui sont-ils ? Allez \u00e0 leur rencontre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos conseillers commerciaux \u00e0 Namur et \u00e0 Tournai | Experts VERANDAIR\" \/>\n<meta property=\"og:description\" content=\"Nos conseillers commerciaux vous aident dans la r\u00e9alisation de votre projet d&#039;abri r\u00e9tractable. Qui sont-ils ? Allez \u00e0 leur rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/\" \/>\n<meta property=\"og:site_name\" content=\"VERANDAIR\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T15:38:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T14:25:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.verandair.com\/wp-content\/uploads\/2020\/12\/showroom-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"olivier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"olivier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/\"},\"author\":{\"name\":\"olivier\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/person\\\/1d5f6f4fbe3d271ab42df18c9d9f06dd\"},\"headline\":\"Nos conseillers commerciaux vous accompagnent dans nos showrooms de Namur et Tournai\",\"datePublished\":\"2021-02-01T15:38:22+00:00\",\"dateModified\":\"2026-02-27T14:25:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/\"},\"wordCount\":1629,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/showroom-3.jpeg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/\",\"name\":\"Nos conseillers commerciaux \u00e0 Namur et \u00e0 Tournai | Experts VERANDAIR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/showroom-3.jpeg\",\"datePublished\":\"2021-02-01T15:38:22+00:00\",\"dateModified\":\"2026-02-27T14:25:59+00:00\",\"description\":\"Nos conseillers commerciaux vous aident dans la r\u00e9alisation de votre projet d'abri r\u00e9tractable. Qui sont-ils ? Allez \u00e0 leur rencontre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/showroom-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/showroom-3.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"conseillers commerciaux\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos conseillers commerciaux vous accompagnent dans nos showrooms de Namur et Tournai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"VERANDAIR\u00ae\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\",\"name\":\"Verandair\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"width\":283,\"height\":127,\"caption\":\"Verandair\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/person\\\/1d5f6f4fbe3d271ab42df18c9d9f06dd\",\"name\":\"olivier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fd7ab82d20e53af3c7645597302628adc6972ddafd4aef328ae4aa64f22753a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fd7ab82d20e53af3c7645597302628adc6972ddafd4aef328ae4aa64f22753a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fd7ab82d20e53af3c7645597302628adc6972ddafd4aef328ae4aa64f22753a?s=96&d=mm&r=g\",\"caption\":\"olivier\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos conseillers commerciaux \u00e0 Namur et \u00e0 Tournai | Experts VERANDAIR","description":"Nos conseillers commerciaux vous aident dans la r\u00e9alisation de votre projet d'abri r\u00e9tractable. Qui sont-ils ? Allez \u00e0 leur rencontre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos conseillers commerciaux \u00e0 Namur et \u00e0 Tournai | Experts VERANDAIR","og_description":"Nos conseillers commerciaux vous aident dans la r\u00e9alisation de votre projet d'abri r\u00e9tractable. Qui sont-ils ? Allez \u00e0 leur rencontre.","og_url":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/","og_site_name":"VERANDAIR\u00ae","article_published_time":"2021-02-01T15:38:22+00:00","article_modified_time":"2026-02-27T14:25:59+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2020\/12\/showroom-3.jpeg","type":"image\/jpeg"}],"author":"olivier","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"olivier","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#article","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/"},"author":{"name":"olivier","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/person\/1d5f6f4fbe3d271ab42df18c9d9f06dd"},"headline":"Nos conseillers commerciaux vous accompagnent dans nos showrooms de Namur et Tournai","datePublished":"2021-02-01T15:38:22+00:00","dateModified":"2026-02-27T14:25:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/"},"wordCount":1629,"commentCount":0,"publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2020\/12\/showroom-3.jpeg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/","url":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/","name":"Nos conseillers commerciaux \u00e0 Namur et \u00e0 Tournai | Experts VERANDAIR","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#primaryimage"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2020\/12\/showroom-3.jpeg","datePublished":"2021-02-01T15:38:22+00:00","dateModified":"2026-02-27T14:25:59+00:00","description":"Nos conseillers commerciaux vous aident dans la r\u00e9alisation de votre projet d'abri r\u00e9tractable. Qui sont-ils ? Allez \u00e0 leur rencontre.","breadcrumb":{"@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#primaryimage","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2020\/12\/showroom-3.jpeg","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2020\/12\/showroom-3.jpeg","width":1280,"height":720,"caption":"conseillers commerciaux"},{"@type":"BreadcrumbList","@id":"https:\/\/www.verandair.com\/fr\/nos-conseillers-commerciaux-vous-accompagnent-dans-nos-showrooms-de-namur-et-tournai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/","name":"Accueil"}},{"@type":"ListItem","position":2,"name":"Nos conseillers commerciaux vous accompagnent dans nos showrooms de Namur et Tournai"}]},{"@type":"WebSite","@id":"https:\/\/www.verandair.com\/fr\/#website","url":"https:\/\/www.verandair.com\/fr\/","name":"VERANDAIR\u00ae","description":"","publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.verandair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.verandair.com\/fr\/#organization","name":"Verandair","url":"https:\/\/www.verandair.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","width":283,"height":127,"caption":"Verandair"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/person\/1d5f6f4fbe3d271ab42df18c9d9f06dd","name":"olivier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2fd7ab82d20e53af3c7645597302628adc6972ddafd4aef328ae4aa64f22753a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fd7ab82d20e53af3c7645597302628adc6972ddafd4aef328ae4aa64f22753a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fd7ab82d20e53af3c7645597302628adc6972ddafd4aef328ae4aa64f22753a?s=96&d=mm&r=g","caption":"olivier"}}]}},"_links":{"self":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/18861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/comments?post=18861"}],"version-history":[{"count":5,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/18861\/revisions"}],"predecessor-version":[{"id":74640,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/18861\/revisions\/74640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media\/17421"}],"wp:attachment":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media?parent=18861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/categories?post=18861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/tags?post=18861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}