{"id":31921,"date":"2022-06-09T10:02:21","date_gmt":"2022-06-09T08:02:21","guid":{"rendered":"https:\/\/www.verandair.com\/?p=31921"},"modified":"2024-09-10T10:00:32","modified_gmt":"2024-09-10T08:00:32","slug":"quelles-autorisations-pour-installer-une-pergola","status":"publish","type":"post","link":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/","title":{"rendered":"Quelles sont les autorisations et la surface accept\u00e9es pour installer une pergola ?"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; admin_label=&#8221;Texte&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span style=\"font-weight: 400;\">Install\u00e9e dans le prolongement de votre maison ou au milieu du jardin, la pergola vous <\/span><b>offre un espace ombrag\u00e9<\/b><span style=\"font-weight: 400;\"> o\u00f9 vous pouvez profiter du beau temps. Mais peut-on <\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/\"><span style=\"font-weight: 400;\">installer une pergola<\/span><\/a><span style=\"font-weight: 400;\"> imm\u00e9diatement, sans autorisation ? Et pour quelle surface ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans certains cas, vous devez <\/span><b>faire une d\u00e9claration <\/b><span style=\"font-weight: 400;\">ou <\/span><b>obtenir un permis<\/b><span style=\"font-weight: 400;\"> pour \u00e9riger votre pergola sur votre terrain. Avec les <\/span><b>diff\u00e9rentes r\u00e9glementations<\/b><span style=\"font-weight: 400;\">, il est parfois compliqu\u00e9 de d\u00e9m\u00eal\u00e9 ce qui est autoris\u00e9 ou non.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C\u2019est pourquoi, dans cet article, VERANDAIR\u00ae vous explique quand il est n\u00e9cessaire d\u2019obtenir un permis de construire pour une pergola, et quelle est la surface autoris\u00e9e pour une <\/span><b>pergola sans permis<\/b><span style=\"font-weight: 400;\">. <\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Soyons pr\u00e9cis : qu\u2019est-ce qu\u2019une pergola ?\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Une pergola est une <\/span><b>structure ouverte<\/b><span style=\"font-weight: 400;\">, g\u00e9n\u00e9ralement constitu\u00e9e de <\/span><b>quatre poteaux et d&#8217;une toiture ajour\u00e9e<\/b><span style=\"font-weight: 400;\">. Plac\u00e9e en ext\u00e9rieur, elle offre un abri partiel du soleil et des intemp\u00e9ries. Elle <\/span><b>se distingue d&#8217;<\/b><a href=\"https:\/\/www.verandair.com\/fr\/veranda\/\"><b>une v\u00e9randa<\/b><\/a><span style=\"font-weight: 400;\"> par sa structure plus l\u00e9g\u00e8re et plus ouverte, car la v\u00e9randa est une structure close.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il existe par ailleurs plusieurs types de pergolas. Chez VERANDAIR\u00ae, vous retrouverez notamment la <\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/pergola-prestige\/\"><span style=\"font-weight: 400;\">pergola Prestige<\/span><\/a><span style=\"font-weight: 400;\">, la <\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/pergola-terrasse-toiture-fixe\/\"><span style=\"font-weight: 400;\">pergola \u00e0 toit fixe<\/span><\/a><span style=\"font-weight: 400;\"> et la<\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/pergola-cabriolet\/\"><span style=\"font-weight: 400;\"> pergola cabriolet<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous r\u00eavez de cet espace ext\u00e9rieur ombrag\u00e9 et convivial pour profiter pleinement de votre terrasse ? Dans les prochaines lignes, nous vous expliquons la<\/span><b> surface de pergola<\/b><span style=\"font-weight: 400;\"> qu\u2019il est possible d\u2019installer <\/span><b>sans permis de construire<\/b><span style=\"font-weight: 400;\">. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.verandair.com\/fr\/pergolas\/&#8221; button_text=&#8221;D\u00e9couvrez nos mod\u00e8les de pergola&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Bouton&#8221; _builder_version=&#8221;4.16&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.27.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><span style=\"font-weight: 400;\">Une pergola sans permis, c\u2019est possible !\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">L&#8217;un des atouts majeurs des pergolas est qu&#8217;elles peuvent \u00eatre install\u00e9es sans permis dans <\/span><b>certaines conditions<\/b><span style=\"font-weight: 400;\"> en Belgique. Toutefois, il est crucial de se conformer aux <\/span><b>r\u00e9glementations<\/b><span style=\"font-weight: 400;\"> pour chacune des <\/span><b>trois r\u00e9gions distinctes<\/b><span style=\"font-weight: 400;\"> : la Wallonie, la Flandre et Bruxelles-Capitale.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chacune de ces r\u00e9gions poss\u00e8de ses <\/span><b>propres r\u00e8gles d&#8217;urbanisme <\/b><span style=\"font-weight: 400;\">et d&#8217;am\u00e9nagement du territoire. Cela signifie que les <\/span><b>exigences<\/b><span style=\"font-weight: 400;\"> pour construire une pergola peuvent<\/span><b> varier <\/b><span style=\"font-weight: 400;\">consid\u00e9rablement <\/span><b>d&#8217;une r\u00e9gion \u00e0 l&#8217;autre<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Votre pergola sans permis en Wallonie\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">En Wallonie, les r\u00e9glementations relatives \u00e0 la <\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/\"><span style=\"font-weight: 400;\">construction de pergolas<\/span><\/a><span style=\"font-weight: 400;\"> sont d\u00e9finies par le <\/span><b>Code Wallon de l&#8217;Am\u00e9nagement du Territoire, de l&#8217;Urbanisme et du Patrimoine<\/b><span style=\"font-weight: 400;\"> (CWATUP). Selon cette l\u00e9gislation, une pergola peut \u00eatre construite <\/span><b>sans permis de construire <\/b><span style=\"font-weight: 400;\">si elle respecte une condition pr\u00e9cise.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La seule condition que vous devez respecter concerne la hauteur. Votre pergola ne doit en effet <\/span><b>pas d\u00e9passer les 3,5 m\u00e8tres de haut<\/b><span style=\"font-weight: 400;\">. En ce qui concerne la surface, il n\u2019y a pas de l\u00e9gislation et donc <\/span><b>pas de limite de surface maximale autoris\u00e9e<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Votre pergola sans permis \u00e0 Bruxelles\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La r\u00e9gion de Bruxelles-Capitale est r\u00e9gie par le <\/span><b>Code Bruxellois de l&#8217;Am\u00e9nagement du Territoire<\/b><span style=\"font-weight: 400;\"> (CoBAT). Les <\/span><b>r\u00e8gles<\/b><span style=\"font-weight: 400;\"> ici sont particuli\u00e8rement <\/span><b>strictes<\/b><span style=\"font-weight: 400;\"> en raison de la densit\u00e9 urbaine et des contraintes architecturales.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C\u2019est pourquoi <\/span><b>toute pergola<\/b><span style=\"font-weight: 400;\"> doit \u00eatre install\u00e9e avec un <\/span><b>permis de construire<\/b><span style=\"font-weight: 400;\"> \u00e0 Bruxelles, qu\u2019importe la surface ou la hauteur. Vous devez \u00e9galement recourir aux<\/span><b> prestations d\u2019un architecte<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Votre pergola sans permis en Flandres<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">En Flandre, les r\u00e8gles d&#8217;urbanisme sont r\u00e9gies par le <\/span><b>Code Flamand de l&#8217;Am\u00e9nagement du Territoire<\/b><span style=\"font-weight: 400;\"> (Vlaamse Codex Ruimtelijke Ordening). Les conditions en mati\u00e8re de construction peuvent \u00eatre l\u00e9g\u00e8rement diff\u00e9rentes de celles en Wallonie. Toutefois, lorsqu\u2019il s\u2019agit de construire une pergola sans permis, la r\u00e8gle reste la m\u00eame : il n\u2019y a <\/span><b>pas de surface maximale autoris\u00e9e<\/b><span style=\"font-weight: 400;\">.\u00a0\u00a0<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; alt=&#8221;Pergola toit fixe ouverte avec vue sur un jardin fleuri&#8221; title_text=&#8221;VERANDAIR-selection-55-pergola-ouverte&#8221; src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/02\/VERANDAIR-selection-55-pergola-ouverte.jpg&#8221; align=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><span style=\"font-weight: 400;\">\u201cSans permis\u201d ou \u201ctout permis\u201d ?\u00a0\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Vous r\u00e9sidez en Wallonie ou en Flandres et les termes \u201cpergola sans permis\u201d vous ont charm\u00e9 ? Vous vous voyez d\u00e9j\u00e0 cr\u00e9er un coin de d\u00e9tente et d&#8217;agr\u00e9ment dans votre jardin ou sur votre patio ? Pas si vite\u2026\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">En Wallonie\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Effectivement, l&#8217;<\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/\"><span style=\"font-weight: 400;\">installation d&#8217;une pergola<\/span><\/a><span style=\"font-weight: 400;\"> ne requiert <\/span><b>pas de permis en Wallonie <\/b><span style=\"font-weight: 400;\">d\u00e8s lors qu&#8217;elle r\u00e9pond aux conditions de superficie, de hauteur et de distance mentionn\u00e9es pr\u00e9c\u00e9demment. Cependant, cela <\/span><b>ne signifie pas<\/b><span style=\"font-weight: 400;\"> que vous avez une <\/span><b>libert\u00e9 totale<\/b><span style=\"font-weight: 400;\"> dans sa conception et sa r\u00e9alisation.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est n\u00e9cessaire pour cela de vous <\/span><b>r\u00e9f\u00e9rer prioritairement \u00e0 votre administration communale<\/b><span style=\"font-weight: 400;\">. De cette mani\u00e8re, vous serez pr\u00e9cis\u00e9ment au courant des l\u00e9gislations en vigueur dans votre commune.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">En Flandres\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Il est important de noter que <\/span><b>certaines communes flamandes <\/b><span style=\"font-weight: 400;\">peuvent avoir des <\/span><b>r\u00e9glementations plus strictes.<\/b><span style=\"font-weight: 400;\"> Les r\u00e9glementations en Flandre peuvent \u00e9galement inclure des <\/span><b>obligations de notification <\/b><span style=\"font-weight: 400;\">pour certaines constructions, m\u00eame si elles ne n\u00e9cessitent pas de permis formel.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est donc toujours prudent de <\/span><b>v\u00e9rifier<\/b><span style=\"font-weight: 400;\"> aupr\u00e8s des<\/span><b> autorit\u00e9s locales<\/b><span style=\"font-weight: 400;\">. La commune pourra vous fournir les informations pr\u00e9cises concernant les r\u00e8gles en vigueur sur son territoire. Elle pourra \u00e9galement vous d\u00e9livrer, si n\u00e9cessaire, une <\/span><b>autorisation sp\u00e9cifique<\/b><span style=\"font-weight: 400;\"> pour l&#8217;installation de votre pergola.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Veillez \u00e0 consulter le site web du Vlaamse Overheid pour plus d\u2019informations.\u00a0<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.verandair.com\/fr\/contact\/&#8221; button_text=&#8221;Demandez un devis pour votre projet&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Bouton&#8221; _builder_version=&#8221;4.27.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><span style=\"font-weight: 400;\">Quels avantages pour la pergola sans permis ?\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Vous connaissez \u00e0 pr\u00e9sent les<\/span><b> conditions n\u00e9cessaires <\/b><span style=\"font-weight: 400;\">pour l\u2019installation d\u2019une pergola sans d\u00e9marches administratives. Vous h\u00e9sitez encore \u00e0<\/span><b> passer le cap <\/b><span style=\"font-weight: 400;\">? VERANDAIR\u00ae\u00a0 vous d\u00e9voile ses<\/span><b> 3 avantages principaux<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Rapidit\u00e9 et simplicit\u00e9 d&#8217;installation<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Oubliez les d\u00e9marches administratives lourdes et les d\u00e9lais d&#8217;attente ! Oui, car les d\u00e9marches administratives pour obtenir un permis de construire peuvent \u00eatre longues et compliqu\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En l&#8217;absence de ces formalit\u00e9s, vous pouvez commencer les travaux d\u00e8s que vous avez d\u00e9cid\u00e9 du design et des mat\u00e9riaux de votre pergola. En bref, vous profiterez de votre nouvel espace ext\u00e9rieur beaucoup plus rapidement !\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Un moindre co\u00fbt\u00a0<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Cela peut sembler \u00e9vident, mais les d\u00e9marches administratives pour obtenir un permis de construire peuvent entra\u00eener des <\/span><b>co\u00fbts suppl\u00e9mentaires<\/b><span style=\"font-weight: 400;\">. Vous vous \u00e9vitez donc les<\/span><b> frais de dossier<\/b><span style=\"font-weight: 400;\">, les <\/span><b>honoraires<\/b><span style=\"font-weight: 400;\"> des professionnels tels que les <\/span><b>architectes<\/b><span style=\"font-weight: 400;\"> ou les <\/span><b>g\u00e9om\u00e8tres<\/b><span style=\"font-weight: 400;\">, et parfois m\u00eame des <\/span><b>co\u00fbts associ\u00e9s<\/b><span style=\"font-weight: 400;\"> \u00e0 des <\/span><b>\u00e9tudes d&#8217;impact<\/b><span style=\"font-weight: 400;\"> ou des <\/span><b>inspections<\/b><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De quoi r\u00e9investir cette somme dans la pergola de vos r\u00eaves !\u00a0<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; button_url=&#8221;https:\/\/www.verandair.com\/fr\/pergolas\/&#8221; button_text=&#8221;D\u00e9couvrez nos mod\u00e8les de pergola&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; button_alignment=&#8221;center&#8221;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3><span style=\"font-weight: 400;\">Flexibilit\u00e9 dans la conception<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Bien s\u00fbr, sans les restrictions impos\u00e9es par un permis de construire, vous gagnez une plus <\/span><b>grande libert\u00e9<\/b><span style=\"font-weight: 400;\"> dans la <\/span><b>conception<\/b><span style=\"font-weight: 400;\"> de votre <\/span><b>pergola<\/b><span style=\"font-weight: 400;\">. Modifiez sa configuration, agrandissez sa surface ou changez son rev\u00eatement sans d\u00e9marches administratives suppl\u00e9mentaires !<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2><span style=\"font-weight: 400;\">Votre pergola sans contrainte avec VERANDAIR\u00ae\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A la question \u201cquelle surface pour une pergola sans permis de construire\u201d, nous vous r\u00e9pondons donc\u2026 qu\u2019il n\u2019y a aucune limite ! Assurez-vous simplement que votre pergola ne d\u00e9passe pas les <\/span><b>3,5 m de hauteur<\/b><span style=\"font-weight: 400;\">. Alors, pr\u00eat \u00e0 <\/span><b>transformer votre jardin <\/b><span style=\"font-weight: 400;\">ou votre <\/span><b>terrasse<\/b><span style=\"font-weight: 400;\"> en un v\u00e9ritable <\/span><b>havre de paix<\/b><span style=\"font-weight: 400;\"> ?\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Avec VERANDAIR\u00ae , <\/span><a href=\"https:\/\/www.verandair.com\/fr\/pergolas\/\"><span style=\"font-weight: 400;\">votre pergola sans permis<\/span><\/a><span style=\"font-weight: 400;\"> est synonyme de <\/span><b>qualit\u00e9<\/b><span style=\"font-weight: 400;\">, de <\/span><b>durabilit\u00e9<\/b><span style=\"font-weight: 400;\"> et d&#8217;<\/span><b>esth\u00e9tique<\/b><span style=\"font-weight: 400;\">. Nos experts vous accompagnent dans <\/span><b>votre projet<\/b><span style=\"font-weight: 400;\">, de la conception \u00e0 la r\u00e9alisation, pour vous garantir une <\/span><b>pergola sur mesure<\/b><span style=\"font-weight: 400;\"> qui r\u00e9pondra parfaitement \u00e0 <\/span><b>vos attentes<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; button_text=&#8221;R\u00e9alisez votre projet &#8221; button_url=&#8221;https:\/\/www.verandair.com\/fr\/contact\/&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; button_alignment=&#8221;center&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;CTA Guide achat Pergola&#8221; _builder_version=&#8221;4.19.2&#8243; background_color=&#8221;#009f9c&#8221; custom_margin=&#8221;|||&#8221; saved_tabs=&#8221;all&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,2_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; padding_top_bottom_link_2=&#8221;false&#8221; padding_left_right_link_1=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|20px||20px&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/11\/guide-achat-pergola.png&#8221; url=&#8221;https:\/\/info.verandair.com\/guide-pergola\/&#8221; url_new_window=&#8221;on&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.19.2&#8243; custom_margin=&#8221;||0px|&#8221; custom_padding=&#8221;|0px||&#8221; custom_css_main_element=&#8221;max-width:280px;&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;30px|30px|0px|30px&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.19.2&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;30px&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;|800|||||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_font_size=&#8221;35px&#8221; custom_margin=&#8221;||20px&#8221; header_3_font_size_tablet=&#8221;25px&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Besoin d&#8217;aide pour vous d\u00e9cider?<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.19.2&#8243; text_font=&#8221;||||||||&#8221; custom_margin=&#8221;||20px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center; font-size: 20px; line-height: 30px;\">Facilitez votre prise de d\u00e9cision avec notre guide d\u2019achat. Il aborde les 19 questions que vous devez absolument vous poser afin de profiter de votre future pergola sans mauvaise surprise.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/info.verandair.com\/guide-pergola\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;\u00bb Je t\u00e9l\u00e9charge mon guide&#8221; button_alignment=&#8221;center&#8221; module_class=&#8221;custom-btn-orange&#8221; _builder_version=&#8221;4.19.2&#8243; custom_margin=&#8221;||0px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_code _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<style><!-- [et_pb_line_break_holder] -->  a.et_pb_button.custom-btn-orange{<!-- [et_pb_line_break_holder] -->    background:#EF865B!important;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] -->  a.et_pb_button.custom-btn-orange:hover{<!-- [et_pb_line_break_holder] -->    background:#F4AD91!important;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand des autorisations sont-elles obligatoires pour installer une pergola en Belgique ? VERANDAIR vous guide \u00e0 travers les r\u00e9glementations en Wallonie, Flandres et Bruxelles.<\/p>\n","protected":false},"author":4,"featured_media":26895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-31921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pergolas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Installer une pergola : les autorisations n\u00e9cessaires | VERANDAIR\u00ae<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez quand un permis est n\u00e9cessaire pour installer une pergola en Belgique et les r\u00e8gles en Wallonie, Flandres, et Bruxelles avec VERANDAIR.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installer une pergola : les autorisations n\u00e9cessaires | VERANDAIR\u00ae\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez quand un permis est n\u00e9cessaire pour installer une pergola en Belgique et les r\u00e8gles en Wallonie, Flandres, et Bruxelles avec VERANDAIR.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/\" \/>\n<meta property=\"og:site_name\" content=\"VERANDAIR\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T08:02:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T08:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/10\/IMG_2120.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"caro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"caro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/\"},\"author\":{\"name\":\"caro\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/person\\\/af737cd43f080163882becebbd86c4db\"},\"headline\":\"Quelles sont les autorisations et la surface accept\u00e9es pour installer une pergola ?\",\"datePublished\":\"2022-06-09T08:02:21+00:00\",\"dateModified\":\"2024-09-10T08:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/\"},\"wordCount\":1835,\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_2120.jpg\",\"articleSection\":[\"Pergolas\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/\",\"name\":\"Installer une pergola : les autorisations n\u00e9cessaires | VERANDAIR\u00ae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_2120.jpg\",\"datePublished\":\"2022-06-09T08:02:21+00:00\",\"dateModified\":\"2024-09-10T08:00:32+00:00\",\"description\":\"D\u00e9couvrez quand un permis est n\u00e9cessaire pour installer une pergola en Belgique et les r\u00e8gles en Wallonie, Flandres, et Bruxelles avec VERANDAIR.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_2120.jpg\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_2120.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Pergola carr\u00e9e \u00e0 toit transparent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/quelles-autorisations-pour-installer-une-pergola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelles sont les autorisations et la surface accept\u00e9es pour installer une pergola ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"VERANDAIR\u00ae\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\",\"name\":\"Verandair\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"width\":283,\"height\":127,\"caption\":\"Verandair\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/person\\\/af737cd43f080163882becebbd86c4db\",\"name\":\"caro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g\",\"caption\":\"caro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Installer une pergola : les autorisations n\u00e9cessaires | VERANDAIR\u00ae","description":"D\u00e9couvrez quand un permis est n\u00e9cessaire pour installer une pergola en Belgique et les r\u00e8gles en Wallonie, Flandres, et Bruxelles avec VERANDAIR.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/","og_locale":"fr_FR","og_type":"article","og_title":"Installer une pergola : les autorisations n\u00e9cessaires | VERANDAIR\u00ae","og_description":"D\u00e9couvrez quand un permis est n\u00e9cessaire pour installer une pergola en Belgique et les r\u00e8gles en Wallonie, Flandres, et Bruxelles avec VERANDAIR.","og_url":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/","og_site_name":"VERANDAIR\u00ae","article_published_time":"2022-06-09T08:02:21+00:00","article_modified_time":"2024-09-10T08:00:32+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/10\/IMG_2120.jpg","type":"image\/jpeg"}],"author":"caro","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"caro","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#article","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/"},"author":{"name":"caro","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/person\/af737cd43f080163882becebbd86c4db"},"headline":"Quelles sont les autorisations et la surface accept\u00e9es pour installer une pergola ?","datePublished":"2022-06-09T08:02:21+00:00","dateModified":"2024-09-10T08:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/"},"wordCount":1835,"publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/10\/IMG_2120.jpg","articleSection":["Pergolas"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/","url":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/","name":"Installer une pergola : les autorisations n\u00e9cessaires | VERANDAIR\u00ae","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#primaryimage"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/10\/IMG_2120.jpg","datePublished":"2022-06-09T08:02:21+00:00","dateModified":"2024-09-10T08:00:32+00:00","description":"D\u00e9couvrez quand un permis est n\u00e9cessaire pour installer une pergola en Belgique et les r\u00e8gles en Wallonie, Flandres, et Bruxelles avec VERANDAIR.","breadcrumb":{"@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#primaryimage","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/10\/IMG_2120.jpg","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2021\/10\/IMG_2120.jpg","width":1200,"height":1200,"caption":"Pergola carr\u00e9e \u00e0 toit transparent"},{"@type":"BreadcrumbList","@id":"https:\/\/www.verandair.com\/fr\/quelles-autorisations-pour-installer-une-pergola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/","name":"Accueil"}},{"@type":"ListItem","position":2,"name":"Quelles sont les autorisations et la surface accept\u00e9es pour installer une pergola ?"}]},{"@type":"WebSite","@id":"https:\/\/www.verandair.com\/fr\/#website","url":"https:\/\/www.verandair.com\/fr\/","name":"VERANDAIR\u00ae","description":"","publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.verandair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.verandair.com\/fr\/#organization","name":"Verandair","url":"https:\/\/www.verandair.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","width":283,"height":127,"caption":"Verandair"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/person\/af737cd43f080163882becebbd86c4db","name":"caro","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g","caption":"caro"}}]}},"_links":{"self":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/31921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/comments?post=31921"}],"version-history":[{"count":4,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/31921\/revisions"}],"predecessor-version":[{"id":64170,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/31921\/revisions\/64170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media\/26895"}],"wp:attachment":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media?parent=31921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/categories?post=31921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/tags?post=31921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}