{"id":55168,"date":"2023-11-18T08:09:22","date_gmt":"2023-11-18T07:09:22","guid":{"rendered":"https:\/\/www.verandair.com\/?p=55168"},"modified":"2024-09-11T12:07:06","modified_gmt":"2024-09-11T10:07:06","slug":"carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte","status":"publish","type":"post","link":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/","title":{"rendered":"Carport solaire avec borne de recharge : L&#8217;avenir de la mobilit\u00e9 verte"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h2>Quand l&#8217;\u00e9lectrique rencontre le solaire<\/h2>\n<p>Avec l&#8217;essor des voitures \u00e9lectriques, le besoin de solutions de recharge \u00e0 domicile n&#8217;a jamais \u00e9t\u00e9 aussi pressant. Mais que diriez-vous si cette solution pouvait \u00e9galement contribuer \u00e0 un avenir plus vert ? Entrez dans l&#8217;univers du <strong>carport solaire<\/strong>, une innovation qui combine protection pour votre v\u00e9hicule et \u00e9nergie renouvelable.<\/p>\n<p>&nbsp;<\/p>\n<h2>Le carport solaire : bien plus qu&#8217;un simple toit<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Au premier abord, un <a href=\"https:\/\/www.verandair.com\/fr\/carport-aluminium\/\">carport solaire<\/a> ressemble \u00e0 n&#8217;importe quel abri pour voiture. Cependant, son toit est loin d&#8217;\u00eatre ordinaire. Le carport solaire est une <strong>solution int\u00e9gr\u00e9e<\/strong> qui, gr\u00e2ce \u00e0 une s\u00e9rie de dispositifs interconnect\u00e9s, permet de capturer l&#8217;<strong>\u00e9nergie solaire<\/strong>, de la stocker et de l&#8217;utiliser pour <strong>recharger votre voiture \u00e9lectrique<\/strong> de mani\u00e8re efficace et \u00e9cologique.<\/p>\n<p>Imaginez rentrer chez vous, garer votre voiture sous votre carport et la voir se recharger gr\u00e2ce \u00e0 l&#8217;\u00e9nergie solaire capt\u00e9e pendant la journ\u00e9e. Non seulement vous b\u00e9n\u00e9ficiez d&#8217;une solution de recharge \u00e0 domicile, mais vous le faites de mani\u00e8re \u00e9cologique.<\/p>\n<p>&nbsp;<\/p>\n<h2>Pourquoi le carport solaire est un bon choix\u00a0?<\/h2>\n<p>Alors que le monde s&#8217;oriente vers des <strong>solutions plus \u00e9cologiques<\/strong>, le carport solaire se pr\u00e9sente comme une r\u00e9ponse \u00e0 la fois pratique et respectueuse de l&#8217;environnement. Voici pourquoi il est temps de consid\u00e9rer cette option pour votre domicile :<\/p>\n<p>&nbsp;<\/p>\n<h3>Impact environnemental r\u00e9duit<\/h3>\n<p>En utilisant l&#8217;\u00e9nergie solaire, une source d&#8217;\u00e9nergie renouvelable, pour recharger votre v\u00e9hicule \u00e9lectrique, vous r\u00e9duisez consid\u00e9rablement votre <strong>empreinte carbone<\/strong>. En effet, chaque kilowatt-heure produit par votre carport solaire est un kilowatt-heure qui n&#8217;est pas g\u00e9n\u00e9r\u00e9 \u00e0 partir de combustibles fossiles.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00c9conomies \u00e0 long terme<\/h3>\n<p>Bien que l&#8217;investissement initial puisse sembler important, les \u00e9conomies r\u00e9alis\u00e9es sur les <strong>factures d&#8217;\u00e9lectricit\u00e9<\/strong> et les <strong>co\u00fbts de recharge<\/strong> compensent rapidement. De plus, dans certaines r\u00e9gions, vous pourriez b\u00e9n\u00e9ficier d&#8217;incitations fiscales ou de <strong>subventions <\/strong>pour l&#8217;installation de solutions solaires.<\/p>\n<p>&nbsp;<\/p>\n<h3>Ind\u00e9pendance \u00e9nerg\u00e9tique<\/h3>\n<p>Avec un carport solaire, vous produisez votre propre \u00e9lectricit\u00e9. Cela vous rend moins d\u00e9pendant des fournisseurs d&#8217;\u00e9nergie et des fluctuations des tarifs.<\/p>\n<p>&nbsp;<\/p>\n<h3>Valorisation de la propri\u00e9t\u00e9<\/h3>\n<p>L&#8217;ajout d&#8217;une installation solaire peut <strong>augmenter la valeur<\/strong> de votre propri\u00e9t\u00e9. C&#8217;est un atout majeur pour les futurs acheteurs, conscients des enjeux environnementaux.<\/p>\n<p>&nbsp;<\/p>\n<h2>Borne de recharge : comment choisir celle qui vous convient ?<\/h2>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/02\/carport-solaire-1.jpg&#8221; alt=&#8221;carport solaire &#8221; title_text=&#8221;carport-solaire-1&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;40px||40px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Avec l&#8217;augmentation du nombre de voitures \u00e9lectriques sur les routes, le march\u00e9 des bornes de recharge a \u00e9galement connu une croissance exponentielle. Voici un peu d\u2019aide pour s\u2019y retrouver parmi toutes ces options:<\/p>\n<ul>\n<li><strong>Type de recharge<\/strong> : Il existe trois principaux types de recharge <strong>&#8211; standard<\/strong>, <strong>semi-rapide<\/strong> et <strong>rapide<\/strong>. Le choix d\u00e9pendra de votre v\u00e9hicule et de vos besoins en mati\u00e8re de recharge. Par exemple, une borne rapide peut recharger votre v\u00e9hicule en moins d&#8217;une heure, mais tous les v\u00e9hicules ne sont pas compatibles avec ce type de recharge.<\/li>\n<li><strong>Compatibilit\u00e9 <\/strong>: Assurez-vous que la borne de recharge est compatible avec votre mod\u00e8le de voiture. Certains connecteurs peuvent ne pas \u00eatre adapt\u00e9s \u00e0 tous les v\u00e9hicules.<\/li>\n<li><strong>Puissance <\/strong>: La puissance de la borne d\u00e9termine la vitesse de recharge. Une borne de 22 kW rechargera votre v\u00e9hicule beaucoup plus rapidement qu&#8217;une borne de 7 kW. Parmi les marques reconnues sur le march\u00e9, on retrouve <a href=\"https:\/\/www.flo.com\/\">FLO<\/a>, <a href=\"https:\/\/www.chargepoint.com\/\">ChargePoint<\/a> et <a href=\"https:\/\/www.elmec.ca\/\">EVduty (Elmec)<\/a>. Il est \u00e9galement possible de consulter des plateformes comme <a href=\"https:\/\/fr.chargemap.com\/map\">Chargemap<\/a> pour trouver les meilleures bornes pour votre voiture \u00e9lectrique.<\/li>\n<li><strong>Installation<\/strong>: Vous devez faire appel \u00e0 un professionnel pour installer votre borne de recharge. Une installation correcte garantira en effet la s\u00e9curit\u00e9 et l&#8217;efficacit\u00e9 du syst\u00e8me.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Verandair : quand l\u2019expertise rencontre l\u2019innovation<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][dsm_image_carousel gallery_ids=&#8221;2131,1876,1875&#8243; sizes=&#8221;medium&#8221; slider_direction=&#8221;rtl&#8221; slide_to_show=&#8221;2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/dsm_image_carousel][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Verandair, reconnu depuis plus de trente ans pour ses solutions d&#8217;abris ext\u00e9rieurs de qualit\u00e9, propose \u00e9galement des carports solaires d&#8217;exception. : Verandair ne se contente pas de fournir des solutions solaires ; l&#8217;entreprise s&#8217;engage \u00e0 offrir des produits qui allient esth\u00e9tique et performance. Voici ce qui distingue les carports solaires Verandair :<\/p>\n<ul>\n<li><strong>Personnalisation<\/strong> : Chaque carport est adapt\u00e9 \u00e0 vos besoins sp\u00e9cifiques, garantissant ainsi une solution parfaitement adapt\u00e9e \u00e0 votre espace et \u00e0 vos pr\u00e9f\u00e9rences.<\/li>\n<li><strong>Mat\u00e9riaux de haute qualit\u00e9<\/strong> : Verandair utilise des mat\u00e9riaux durables et r\u00e9sistants pour garantir la long\u00e9vit\u00e9 de <a href=\"https:\/\/www.verandair.com\/fr\/carport-aluminium\/\">votre carport<\/a>.<\/li>\n<li><strong>Int\u00e9gration harmonieuse<\/strong> : Le design des carports Verandair est pens\u00e9 pour s&#8217;int\u00e9grer naturellement \u00e0 votre environnement, qu&#8217;il s&#8217;agisse d&#8217;une maison moderne ou d&#8217;une demeure plus traditionnelle.<\/li>\n<li><strong>Garantie<\/strong> : La confiance que Verandair a dans la qualit\u00e9 de ses produits se refl\u00e8te dans la garantie offerte, vous assurant ainsi une tranquillit\u00e9 d&#8217;esprit.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>L&#8217;\u00e9nergie solaire, une r\u00e9ponse \u00e0 la mobilit\u00e9 de demain<\/h2>\n<p>La transition vers des modes de transport plus \u00e9cologiques est en marche, et avec elle, le besoin de solutions de recharge innovantes et durables. Le <a href=\"https:\/\/www.verandair.com\/fr\/carport-aluminium\/\">carport<\/a> solaire avec borne de recharge, propos\u00e9 par Verandair, est plus qu&#8217;une simple innovation : c&#8217;est une r\u00e9ponse concr\u00e8te aux d\u00e9fis de la mobilit\u00e9 \u00e9lectrique. En combinant esth\u00e9tique, fonctionnalit\u00e9 et respect de l&#8217;environnement, il s&#8217;impose comme un choix incontournable pour tous ceux qui souhaitent conjuguer mobilit\u00e9 et durabilit\u00e9.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.2&#8243; background_color=&#8221;#f2f2f2&#8243; custom_padding=&#8221;10px||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#f2f2f2&#8243; custom_padding=&#8221;30px|30px|10px|30px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; module_class=&#8221;callto&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; custom_css_main_element=&#8221;margin: auto;&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; text_text_color=&#8221;#494949&#8243; text_font_size=&#8221;29px&#8221; custom_margin=&#8221;||0px|&#8221; custom_padding=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3 style=\"text-align: center;\">Alors, pourquoi attendre ?<\/h3>\n<h3 style=\"text-align: center;\">D\u00e9couvrez d\u00e8s aujourd&#8217;hui comment Verandair peut transformer votre espace ext\u00e9rieur et contribuer \u00e0 un avenir plus vert.<\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.verandair.com\/fr\/carport-aluminium\/&#8221; button_text=&#8221;D\u00e9couvrez les produits Verandair ici&#8221; button_alignment=&#8221;center&#8221; module_id=&#8221;calltobtnn&#8221; _builder_version=&#8221;4.24.2&#8243; custom_margin=&#8221;20px||0px|&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rechargez votre \u00e9lectrique gr\u00e2ce au soleil! Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte. <\/p>\n","protected":false},"author":4,"featured_media":55165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-55168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carport solaire &amp; borne de recharge : la solution pour voiture \u00e9lectrique<\/title>\n<meta name=\"description\" content=\"Rechargez votre \u00e9lectrique gr\u00e2ce au soleil \u2600\ufe0f Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carport solaire &amp; borne de recharge : la solution pour voiture \u00e9lectrique\" \/>\n<meta property=\"og:description\" content=\"Rechargez votre \u00e9lectrique gr\u00e2ce au soleil \u2600\ufe0f Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/\" \/>\n<meta property=\"og:site_name\" content=\"VERANDAIR\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-18T07:09:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T10:07:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.verandair.com\/wp-content\/uploads\/2023\/10\/carport-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1195\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"caro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"caro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/\"},\"author\":{\"name\":\"caro\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/person\\\/af737cd43f080163882becebbd86c4db\"},\"headline\":\"Carport solaire avec borne de recharge : L&#8217;avenir de la mobilit\u00e9 verte\",\"datePublished\":\"2023-11-18T07:09:22+00:00\",\"dateModified\":\"2024-09-11T10:07:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/\"},\"wordCount\":1379,\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/carport-1.jpg\",\"articleSection\":[\"Carport\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/\",\"name\":\"Carport solaire & borne de recharge : la solution pour voiture \u00e9lectrique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/carport-1.jpg\",\"datePublished\":\"2023-11-18T07:09:22+00:00\",\"dateModified\":\"2024-09-11T10:07:06+00:00\",\"description\":\"Rechargez votre \u00e9lectrique gr\u00e2ce au soleil \u2600\ufe0f Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/carport-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/carport-1.jpg\",\"width\":1195,\"height\":792,\"caption\":\"Caport solaire avec des panneaux \u00e0 l'arri\u00e8re d'une maison blanche moderne.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carport solaire avec borne de recharge : L&#8217;avenir de la mobilit\u00e9 verte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"name\":\"VERANDAIR\u00ae\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#organization\",\"name\":\"Verandair\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.verandair.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/VERANDAIR-logo.png\",\"width\":283,\"height\":127,\"caption\":\"Verandair\"},\"image\":{\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.verandair.com\\\/fr\\\/#\\\/schema\\\/person\\\/af737cd43f080163882becebbd86c4db\",\"name\":\"caro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g\",\"caption\":\"caro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carport solaire & borne de recharge : la solution pour voiture \u00e9lectrique","description":"Rechargez votre \u00e9lectrique gr\u00e2ce au soleil \u2600\ufe0f Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/","og_locale":"fr_FR","og_type":"article","og_title":"Carport solaire & borne de recharge : la solution pour voiture \u00e9lectrique","og_description":"Rechargez votre \u00e9lectrique gr\u00e2ce au soleil \u2600\ufe0f Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte.","og_url":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/","og_site_name":"VERANDAIR\u00ae","article_published_time":"2023-11-18T07:09:22+00:00","article_modified_time":"2024-09-11T10:07:06+00:00","og_image":[{"width":1195,"height":792,"url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2023\/10\/carport-1.jpg","type":"image\/jpeg"}],"author":"caro","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"caro","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#article","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/"},"author":{"name":"caro","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/person\/af737cd43f080163882becebbd86c4db"},"headline":"Carport solaire avec borne de recharge : L&#8217;avenir de la mobilit\u00e9 verte","datePublished":"2023-11-18T07:09:22+00:00","dateModified":"2024-09-11T10:07:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/"},"wordCount":1379,"publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2023\/10\/carport-1.jpg","articleSection":["Carport"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/","url":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/","name":"Carport solaire & borne de recharge : la solution pour voiture \u00e9lectrique","isPartOf":{"@id":"https:\/\/www.verandair.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#primaryimage"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2023\/10\/carport-1.jpg","datePublished":"2023-11-18T07:09:22+00:00","dateModified":"2024-09-11T10:07:06+00:00","description":"Rechargez votre \u00e9lectrique gr\u00e2ce au soleil \u2600\ufe0f Le carport solaire avec borne int\u00e9gr\u00e9e, une r\u00e9volution pour la mobilit\u00e9 verte.","breadcrumb":{"@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#primaryimage","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2023\/10\/carport-1.jpg","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2023\/10\/carport-1.jpg","width":1195,"height":792,"caption":"Caport solaire avec des panneaux \u00e0 l'arri\u00e8re d'une maison blanche moderne."},{"@type":"BreadcrumbList","@id":"https:\/\/www.verandair.com\/fr\/carport-solaire-avec-borne-de-recharge-lavenir-de-la-mobilite-verte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":{"@type":"WebPage","@id":"https:\/\/www.verandair.com\/fr\/","name":"Accueil"}},{"@type":"ListItem","position":2,"name":"Carport solaire avec borne de recharge : L&#8217;avenir de la mobilit\u00e9 verte"}]},{"@type":"WebSite","@id":"https:\/\/www.verandair.com\/fr\/#website","url":"https:\/\/www.verandair.com\/fr\/","name":"VERANDAIR\u00ae","description":"","publisher":{"@id":"https:\/\/www.verandair.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.verandair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.verandair.com\/fr\/#organization","name":"Verandair","url":"https:\/\/www.verandair.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","contentUrl":"https:\/\/www.verandair.com\/wp-content\/uploads\/2024\/06\/VERANDAIR-logo.png","width":283,"height":127,"caption":"Verandair"},"image":{"@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.verandair.com\/fr\/#\/schema\/person\/af737cd43f080163882becebbd86c4db","name":"caro","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c356829a7552d3573f0151ea3bcc417616acba472a5e3565de5ae3a5b614aab?s=96&d=mm&r=g","caption":"caro"}}]}},"_links":{"self":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/55168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/comments?post=55168"}],"version-history":[{"count":8,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/55168\/revisions"}],"predecessor-version":[{"id":64261,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/posts\/55168\/revisions\/64261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media\/55165"}],"wp:attachment":[{"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/media?parent=55168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/categories?post=55168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.verandair.com\/fr\/wp-json\/wp\/v2\/tags?post=55168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}